{"id":589,"count":1,"description":"","link":"https:\/\/taxialicante.co.uk\/en\/tag\/dolia-en\/","name":"dolia","slug":"dolia-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>dolia Archives - Taxi Alicante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"dolia Archives - Taxi Alicante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Taxi Alicante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/\",\"url\":\"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/\",\"name\":\"dolia Archives - Taxi Alicante\",\"isPartOf\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/#breadcrumb\"},\"inLanguage\":\"en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/taxialicante.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"dolia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#website\",\"url\":\"https:\/\/taxialicante.eu\/fr\/\",\"name\":\"Taxi Alicante\",\"description\":\"25 jaar ervaring in luchthavenvervoer\",\"publisher\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/taxialicante.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#organization\",\"name\":\"Taxi Alicante\",\"url\":\"https:\/\/taxialicante.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png\",\"contentUrl\":\"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png\",\"width\":350,\"height\":84,\"caption\":\"Taxi Alicante\"},\"image\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/taxialicantevalencia\/?fref=ts\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"dolia Archives - Taxi Alicante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"dolia Archives - Taxi Alicante","og_url":"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/","og_site_name":"Taxi Alicante","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/","url":"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/","name":"dolia Archives - Taxi Alicante","isPartOf":{"@id":"https:\/\/taxialicante.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/#breadcrumb"},"inLanguage":"en"},{"@type":"BreadcrumbList","@id":"https:\/\/taxialicante.eu\/en\/tag\/dolia-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taxialicante.eu\/en\/"},{"@type":"ListItem","position":2,"name":"dolia"}]},{"@type":"WebSite","@id":"https:\/\/taxialicante.eu\/fr\/#website","url":"https:\/\/taxialicante.eu\/fr\/","name":"Taxi Alicante","description":"25 jaar ervaring in luchthavenvervoer","publisher":{"@id":"https:\/\/taxialicante.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taxialicante.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/taxialicante.eu\/fr\/#organization","name":"Taxi Alicante","url":"https:\/\/taxialicante.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png","contentUrl":"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png","width":350,"height":84,"caption":"Taxi Alicante"},"image":{"@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/taxialicantevalencia\/?fref=ts"]}]}},"_links":{"self":[{"href":"https:\/\/taxialicante.co.uk\/en\/wp-json\/wp\/v2\/tags\/589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taxialicante.co.uk\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/taxialicante.co.uk\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/taxialicante.co.uk\/en\/wp-json\/wp\/v2\/posts?tags=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}