{"id":4172,"date":"2018-10-03T09:40:43","date_gmt":"2018-10-03T09:40:43","guid":{"rendered":"http:\/\/www.taxialicante.eu\/2018\/10\/03\/oktoberfest-calpe-2018\/"},"modified":"2018-10-03T13:28:17","modified_gmt":"2018-10-03T13:28:17","slug":"oktoberfest-calpe-2018","status":"publish","type":"post","link":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/","title":{"rendered":"Oktoberfest Calpe 2018"},"content":{"rendered":"<p>Cette ann\u00e9e Calpe accueillera la 31\u00e8me \u00e9dition de Oktoberfest du 24 octobre au 4 novembre. Des milliers de personnes se pr\u00e9sentent chaque ann\u00e9e \u00e0 cette \u201cf\u00eate de la bi\u00e8re\u201d pour \u00e9couter de la musique typique en direct, go\u00fbter les diff\u00e9rentes bi\u00e8res allemandes et la nourriture traditionnelle.<\/p>\n<p>La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re. Cette apr\u00e8s-midi, avec l\u2019ouverture du baril commencement plus de 10 jours d\u2019\u00e9v\u00e9nements et de musique.<\/p>\n<p>Chaque apr\u00e8s-midi \u00e0 dix-huit heures, on ouvre les portes du chapiteau de 15.000 m\u00e8tres et les visiteurs peuvent danser, chanter et se sentir un peu plus pr\u00e8s du pays allemand.<\/p>\n<p>La f\u00eate de Calpe, qui a toujours eu un tr\u00e8s bon accueil entre les villageois et les r\u00e9sidents allemands de la localit\u00e9 a aussi su combiner l\u2019esprit allemand avec le go\u00fbt espagnol, car il ne faut pas oublier que cette f\u00eate de bi\u00e8re est c\u00e9l\u00e9br\u00e9e dans des terres d\u2019Alicante, et beaucoup des concours qui sont c\u00e9l\u00e9br\u00e9s durant ces jours ont un caract\u00e8re m\u00e9diterran\u00e9en.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e Calpe accueillera la 31\u00e8me \u00e9dition de Oktoberfest du 24 octobre au 4 novembre. Des milliers de personnes se pr\u00e9sentent chaque ann\u00e9e \u00e0 cette \u201cf\u00eate de la bi\u00e8re\u201d pour \u00e9couter de la musique typique en direct, go\u00fbter les diff\u00e9rentes bi\u00e8res allemandes et la nourriture traditionnelle. La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re. Cette apr\u00e8s-midi, avec l\u2019ouverture du baril commencement plus de 10 jours d\u2019\u00e9v\u00e9nements et de musique. Chaque apr\u00e8s-midi \u00e0 dix-huit heures, on ouvre les portes du chapiteau de 15.000 m\u00e8tres et les visiteurs peuvent danser, chanter et se sentir un peu plus pr\u00e8s du pays allemand. La f\u00eate de Calpe, qui a toujours eu un tr\u00e8s bon accueil entre les villageois et les r\u00e9sidents allemands de la localit\u00e9 a aussi su combiner l\u2019esprit allemand avec le go\u00fbt espagnol, car il ne faut pas oublier que cette f\u00eate de bi\u00e8re est c\u00e9l\u00e9br\u00e9e dans des terres d\u2019Alicante, et beaucoup des concours qui sont c\u00e9l\u00e9br\u00e9s durant ces jours ont un caract\u00e8re m\u00e9diterran\u00e9en.<\/p>\n","protected":false},"author":1,"featured_media":4169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[381,217,177,185,180,382,383],"class_list":["post-4172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-costablanca","tag-bierfeest-fr","tag-calpe","tag-costa-blanca-fr","tag-espagne-fr","tag-featured-fr","tag-oktober-fest-fr","tag-oktoberfest-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oktoberfest Calpe 2018 - Taxi Alicante<\/title>\n<meta name=\"description\" content=\"La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oktoberfest Calpe 2018 - Taxi Alicante\" \/>\n<meta property=\"og:description\" content=\"La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Taxi Alicante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/taxialicantevalencia\/?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-03T09:40:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-03T13:28:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Taxi Alicante\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Taxi Alicante\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/\"},\"author\":{\"name\":\"Taxi Alicante\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/person\/1d9057877c73caba4def8d499d4c3d90\"},\"headline\":\"Oktoberfest Calpe 2018\",\"datePublished\":\"2018-10-03T09:40:43+00:00\",\"dateModified\":\"2018-10-03T13:28:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg\",\"keywords\":[\"bierfeest\",\"calpe\",\"costa blanca\",\"espagne\",\"featured\",\"oktober fest\",\"oktoberfest\"],\"articleSection\":[\"\u00c9v\u00e8nements\"],\"inLanguage\":\"fr\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/\",\"url\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/\",\"name\":\"Oktoberfest Calpe 2018 - Taxi Alicante\",\"isPartOf\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg\",\"datePublished\":\"2018-10-03T09:40:43+00:00\",\"dateModified\":\"2018-10-03T13:28:17+00:00\",\"description\":\"La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#breadcrumb\"},\"inLanguage\":\"fr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage\",\"url\":\"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg\",\"contentUrl\":\"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg\",\"width\":800,\"height\":350,\"caption\":\"oktober fest calpe 2018\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/taxialicante.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oktoberfest Calpe 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#website\",\"url\":\"https:\/\/taxialicante.eu\/fr\/\",\"name\":\"Taxi Alicante\",\"description\":\"25 jaar ervaring in luchthavenvervoer\",\"publisher\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/taxialicante.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#organization\",\"name\":\"Taxi Alicante\",\"url\":\"https:\/\/taxialicante.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png\",\"contentUrl\":\"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png\",\"width\":350,\"height\":84,\"caption\":\"Taxi Alicante\"},\"image\":{\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/taxialicantevalencia\/?fref=ts\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/person\/1d9057877c73caba4def8d499d4c3d90\",\"name\":\"Taxi Alicante\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\/\/taxialicante.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/643d740b11cc02a040a6cf787d5ed09df40e0ca8bdf8d79153fa12211f8de733?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/643d740b11cc02a040a6cf787d5ed09df40e0ca8bdf8d79153fa12211f8de733?s=96&d=mm&r=g\",\"caption\":\"Taxi Alicante\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oktoberfest Calpe 2018 - Taxi Alicante","description":"La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Oktoberfest Calpe 2018 - Taxi Alicante","og_description":"La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re.","og_url":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/","og_site_name":"Taxi Alicante","article_publisher":"https:\/\/www.facebook.com\/taxialicantevalencia\/?fref=ts","article_published_time":"2018-10-03T09:40:43+00:00","article_modified_time":"2018-10-03T13:28:17+00:00","og_image":[{"width":800,"height":350,"url":"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg","type":"image\/jpeg"}],"author":"Taxi Alicante","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Taxi Alicante","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#article","isPartOf":{"@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/"},"author":{"name":"Taxi Alicante","@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/person\/1d9057877c73caba4def8d499d4c3d90"},"headline":"Oktoberfest Calpe 2018","datePublished":"2018-10-03T09:40:43+00:00","dateModified":"2018-10-03T13:28:17+00:00","mainEntityOfPage":{"@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/"},"wordCount":211,"publisher":{"@id":"https:\/\/taxialicante.eu\/fr\/#organization"},"image":{"@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg","keywords":["bierfeest","calpe","costa blanca","espagne","featured","oktober fest","oktoberfest"],"articleSection":["\u00c9v\u00e8nements"],"inLanguage":"fr"},{"@type":"WebPage","@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/","url":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/","name":"Oktoberfest Calpe 2018 - Taxi Alicante","isPartOf":{"@id":"https:\/\/taxialicante.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage"},"image":{"@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg","datePublished":"2018-10-03T09:40:43+00:00","dateModified":"2018-10-03T13:28:17+00:00","description":"La f\u00eate de Calpe, qui se c\u00e9l\u00e8bre depuis 1987, est inaugur\u00e9e par le maire le premier jour avec l\u2019ouverture du premier baril de bi\u00e8re.","breadcrumb":{"@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#breadcrumb"},"inLanguage":"fr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/"]}]},{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#primaryimage","url":"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg","contentUrl":"https:\/\/taxialicante.co.uk\/wp-content\/uploads\/2018\/10\/oktoberfestcalpe2018.jpg","width":800,"height":350,"caption":"oktober fest calpe 2018"},{"@type":"BreadcrumbList","@id":"https:\/\/taxialicante.co.uk\/fr\/2018\/10\/03\/oktoberfest-calpe-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/taxialicante.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Oktoberfest Calpe 2018"}]},{"@type":"WebSite","@id":"https:\/\/taxialicante.eu\/fr\/#website","url":"https:\/\/taxialicante.eu\/fr\/","name":"Taxi Alicante","description":"25 jaar ervaring in luchthavenvervoer","publisher":{"@id":"https:\/\/taxialicante.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taxialicante.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr"},{"@type":"Organization","@id":"https:\/\/taxialicante.eu\/fr\/#organization","name":"Taxi Alicante","url":"https:\/\/taxialicante.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png","contentUrl":"https:\/\/taxialicante.eu\/wp-content\/uploads\/2017\/02\/logo-red-1.png","width":350,"height":84,"caption":"Taxi Alicante"},"image":{"@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/taxialicantevalencia\/?fref=ts"]},{"@type":"Person","@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/person\/1d9057877c73caba4def8d499d4c3d90","name":"Taxi Alicante","image":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/taxialicante.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/643d740b11cc02a040a6cf787d5ed09df40e0ca8bdf8d79153fa12211f8de733?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/643d740b11cc02a040a6cf787d5ed09df40e0ca8bdf8d79153fa12211f8de733?s=96&d=mm&r=g","caption":"Taxi Alicante"}}]}},"_links":{"self":[{"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/posts\/4172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/comments?post=4172"}],"version-history":[{"count":0,"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/posts\/4172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/media\/4169"}],"wp:attachment":[{"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/media?parent=4172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/categories?post=4172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taxialicante.co.uk\/fr\/wp-json\/wp\/v2\/tags?post=4172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}